{"id":28634,"date":"2025-12-23T11:25:22","date_gmt":"2025-12-23T11:25:22","guid":{"rendered":"https:\/\/www.atlanticoprorealestate.com\/?post_type=property&#038;p=28634"},"modified":"2026-04-30T17:17:53","modified_gmt":"2026-04-30T17:17:53","slug":"edificio-lodge-i-torrinha-apartamento-t1-no-centro-do-funchal-4","status":"publish","type":"property","link":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/propriedades\/edificio-lodge-i-torrinha-apartamento-t1-no-centro-do-funchal-4\/","title":{"rendered":"Edif\u00edcio Lodge I Torrinha &#8211; Apartamento T1 no centro do Funchal!"},"content":{"rendered":"<p>Situado na zona de Santa Luzia, o Lodge | Torrinha, beneficia de uma localiza\u00e7\u00e3o privilegiada. Conhecida pela sua proximidade ao centro da cidade, a zona tem assistido a um desenvolvimento significativo, mantendo a sua autenticidade, enquanto se afirma como uma \u00e1rea em crescimento, com novas infraestruturas e f\u00e1cil acesso a servi\u00e7os e comodidades essenciais.<\/p>\n<p>O Lodge | Torrinha \u00e9 composto por 106 apartamentos distribu\u00eddos em dois edif\u00edcios de 6 pisos, oferecendo tipologias T1, T2 e T3. Todos os apartamentos incluem varandas e floreiras, e algumas fra\u00e7\u00f5es contam ainda com terra\u00e7os, jardins privativos e vistas panor\u00e2micas sobre a ba\u00eda do Funchal. Incluem tamb\u00e9m cozinhas e lavandarias totalmente equipadas, pr\u00e9-instala\u00e7\u00e3o de ar condicionado, e os quartos s\u00e3o su\u00edtes (com WC inclu\u00eddo).<\/p>\n<p>As \u00e1reas comuns de cada um dos edif\u00edcios disp\u00f5em de um rooftop com sol\u00e1rio e piscina com vistas panor\u00e2micas para a cidade e para o mar. As \u00e1reas ajardinadas complementam a viv\u00eancia nos apartamentos, proporcionando aos residentes o cen\u00e1rio ideal para momentos de lazer e descontra\u00e7\u00e3o, num ambiente sofisticado e relaxante.<\/p>\n<p>Caracter\u00edsticas do empreendimento:<\/p>\n<p>\u2022 Tipologias T1, T2 e T3<br \/>\n\u2022 Todos os quartos s\u00e3o suite<br \/>\n\u2022 Casa de banho social<br \/>\n\u2022 Cozinha e lavandaria totalmente equipada<br \/>\n\u2022 Pr\u00e9-instala\u00e7\u00e3o de ar condicionado<br \/>\n\u2022 Pain\u00e9is fotovoltaicos e bomba de calor<br \/>\n\u2022 Materiais de grande qualidade e durabilidade<br \/>\n\u2022 Exteriores em bet\u00e3o \u00e0 vista, vidro e a\u00e7o, sem pintura ou revestimentos de pouca durabilidade<br \/>\n\u2022 Varandas e floreiras em todas as fra\u00e7\u00f5es<br \/>\n\u2022 Terra\u00e7os e jardins privativos<br \/>\n\u2022 Rooftop com sol\u00e1rio, piscina comum e vista baia do Funchal<br \/>\n\u2022 Estacionamento coberto, com carregamento el\u00e9trico independente em todos os lugares<br \/>\n\u2022 Um lugar de estacionamento por quarto (T1 com 2 lugares opcional)<\/p>\n<p>Caracter\u00edsticas dos apartamentos T1:<\/p>\n<p>Os apartamentos de tipologia T1 possuem \u00e1reas de 86 a 340 metros quadrados e pre\u00e7os desde 350.000 a 675.000 euros.<\/p>\n<p>Modalidades: Standard, com 1 estacionamento (com possibilidade de aquisi\u00e7\u00e3o de mais 1) e 1 arrecada\u00e7\u00e3o.<\/p>\n<p>Cozinha totalmente equipada, pr\u00e9-instala\u00e7\u00e3o de ar condicionado, o quarto \u00e9 suite, rooftop com jardins, sol\u00e1rio e piscina infinita comum.<\/p>\n<p>** FRA\u00c7\u00c3O 89 | PISO 5| BLOCO POENTE**<\/p>\n<p>LODGE | TORRINHA &#8211; ONDE A VIDA URBANA SENTE A SIMPLICIDADE DO CONFORTO!<\/p>\n<p>Contacte para mais informa\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situado na zona de Santa Luzia, o Lodge | Torrinha, beneficia de uma localiza\u00e7\u00e3o privilegiada. Conhecida pela sua proximidade ao centro da cidade, a zona tem assistido a um desenvolvimento significativo, mantendo a sua autenticidade, enquanto se afirma como uma \u00e1rea em crescimento, com novas infraestruturas e f\u00e1cil acesso a servi\u00e7os e comodidades essenciais. O [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":30940,"parent":0,"menu_order":0,"template":"","property_type":[134,407],"property_status":[402],"property_feature":[315],"property_label":[688],"property_country":[390],"property_state":[341],"property_city":[695],"property_area":[696],"class_list":["post-28634","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-apartamentos","property_type-condominio","property_status-para-venda","property_feature-vista-mar","property_label-funchal-2","property_country-portugal-pt","property_state-ilha-da-madeira","property_city-santa-luzia-2","property_area-torrinha-2"],"property_meta":{"rank_math_internal_links_processed":["1"],"_alp_processed":["1777569473"],"_wpml_word_count":["{\"total\":423,\"to_translate\":{\"en\":423}}"],"_edit_lock":["1777569447:9"],"_edit_last":["9"],"rank_math_seo_score":["12"],"rank_math_contentai_score":["a:5:{s:8:\"keywords\";s:5:\"74.51\";s:9:\"wordCount\";s:1:\"0\";s:9:\"linkCount\";s:1:\"0\";s:12:\"headingCount\";s:1:\"0\";s:10:\"mediaCount\";s:1:\"0\";}"],"fave_property_price":["500000"],"fave_property_size":["90,80"],"fave_property_bedrooms":["1"],"fave_property_bathrooms":["2"],"fave_property_id":["KWPT-017985"],"fave_property_map":["1"],"fave_property_map_address":["Caminho da Torrinha, Livramento, Monte, Curral dos Romeiros, Funchal, Madeira, 9050-293, Portugal"],"fave_property_location":["32.6677848,-16.9065891,15"],"houzez_geolocation_lat":["32.6677848"],"houzez_geolocation_long":["-16.9065891"],"fave_property_map_street_view":["hide"],"fave_property_address":["Caminho da Torrinha, 2"],"fave_property_zip":["9050-293"],"fave_featured":["0"],"fave_loggedintoview":["0"],"fave_video_url":["https:\/\/youtu.be\/msJVkssKlBQ?si=bQdBj_kTG9QZ6bVN"],"fave_agent_display_option":["agent_info"],"fave_agents":["21275"],"fave_prop_homeslider":["no"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"rank_math_primary_property_type":["0"],"rank_math_primary_property_status":["0"],"rank_math_primary_property_feature":["0"],"rank_math_primary_property_label":["0"],"rank_math_primary_property_country":["0"],"rank_math_primary_property_state":["0"],"rank_math_primary_property_city":["0"],"rank_math_primary_property_area":["0"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"fave_payment_status":["not_paid"],"rank_math_analytic_object_id":["939"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"houzez_total_property_views":["264"],"houzez_views_by_date":["a:61:{s:10:\"04-11-2026\";i:3;s:10:\"04-12-2026\";i:2;s:10:\"04-14-2026\";i:2;s:10:\"04-15-2026\";i:6;s:10:\"04-18-2026\";i:1;s:10:\"04-19-2026\";i:1;s:10:\"04-21-2026\";i:2;s:10:\"04-24-2026\";i:2;s:10:\"04-25-2026\";i:1;s:10:\"04-27-2026\";i:1;s:10:\"04-28-2026\";i:3;s:10:\"04-29-2026\";i:1;s:10:\"04-30-2026\";i:1;s:10:\"05-01-2026\";i:1;s:10:\"05-02-2026\";i:1;s:10:\"05-03-2026\";i:1;s:10:\"05-04-2026\";i:2;s:10:\"05-05-2026\";i:3;s:10:\"05-06-2026\";i:3;s:10:\"05-07-2026\";i:1;s:10:\"05-09-2026\";i:3;s:10:\"05-10-2026\";i:3;s:10:\"05-12-2026\";i:2;s:10:\"05-14-2026\";i:3;s:10:\"05-15-2026\";i:2;s:10:\"05-17-2026\";i:1;s:10:\"05-20-2026\";i:1;s:10:\"05-21-2026\";i:1;s:10:\"05-22-2026\";i:1;s:10:\"05-23-2026\";i:2;s:10:\"05-24-2026\";i:1;s:10:\"05-27-2026\";i:1;s:10:\"05-29-2026\";i:1;s:10:\"05-30-2026\";i:1;s:10:\"05-31-2026\";i:3;s:10:\"06-04-2026\";i:1;s:10:\"06-08-2026\";i:1;s:10:\"06-09-2026\";i:2;s:10:\"06-10-2026\";i:3;s:10:\"06-11-2026\";i:1;s:10:\"06-13-2026\";i:2;s:10:\"06-16-2026\";i:1;s:10:\"06-18-2026\";i:2;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:1;s:10:\"06-23-2026\";i:2;s:10:\"06-24-2026\";i:1;s:10:\"06-25-2026\";i:2;s:10:\"06-26-2026\";i:1;s:10:\"06-30-2026\";i:2;s:10:\"07-01-2026\";i:1;s:10:\"07-02-2026\";i:1;s:10:\"07-03-2026\";i:1;s:10:\"07-04-2026\";i:2;s:10:\"07-05-2026\";i:2;s:10:\"07-08-2026\";i:2;s:10:\"07-10-2026\";i:3;s:10:\"07-12-2026\";i:1;s:10:\"07-13-2026\";i:2;s:10:\"07-14-2026\";i:2;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 14:27:47"],"_thumbnail_id":["30940"],"_elementor_css":["a:7:{s:4:\"time\";i:1766488994;s:5:\"fonts\";a:0:{}s:5:\"icons\";a:0:{}s:20:\"dynamic_elements_ids\";a:0:{}s:6:\"status\";s:5:\"empty\";i:0;s:0:\"\";s:3:\"css\";s:0:\"\";}"],"fave_property_images":["30928","30930","30932","30934","30936","30938","30940","30942","30944","30946","30948","30950","30952","30954","30956","30958","30960","30962","30964","30966","30968","30970","30972","30974","30976","30978","30980","30984","30982","30986","30988"]},"_links":{"self":[{"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/properties\/28634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":1,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/properties\/28634\/revisions"}],"predecessor-version":[{"id":28635,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/properties\/28634\/revisions\/28635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/media\/30940"}],"wp:attachment":[{"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=28634"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_type?post=28634"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_status?post=28634"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_feature?post=28634"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_label?post=28634"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_country?post=28634"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_state?post=28634"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_city?post=28634"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/www.atlanticoprorealestate.com\/pt-pt\/wp-json\/wp\/v2\/property_area?post=28634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}